{"id":4013,"date":"2024-07-06T19:57:16","date_gmt":"2024-07-06T17:57:16","guid":{"rendered":"https:\/\/taxis-villefontaine.com\/taxi-pour-femme-a-aeroport-lyon-saint-exupery\/"},"modified":"2024-07-06T19:57:16","modified_gmt":"2024-07-06T17:57:16","slug":"taxi-pour-femme-a-aeroport-lyon-saint-exupery","status":"publish","type":"page","link":"https:\/\/k-miles.fr\/en\/taxi-pour-femme-a-aeroport-lyon-saint-exupery\/","title":{"rendered":"Taxi pour femme \u00e0 A\u00e9roport Lyon Saint-Exupery"},"content":{"rendered":"<div data-elementor-type=\"section\" data-elementor-id=\"2039\" class=\"elementor elementor-2039\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-97d6d24 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"97d6d24\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-04ca31e\" data-id=\"04ca31e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c54c953 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c54c953\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-96e3ff2 elementor-invisible\" data-id=\"96e3ff2\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c94d7b elementor-widget elementor-widget-shortcode\" data-id=\"7c94d7b\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">    <h2>Bienvenue chez Taxi A\u00e9roport Lyon Saint-Exupery<\/h2>\r\n\r\n        <p class=\"landing-page-intro\">Bien vous servir est notre priorit\u00e9 ! Nous sommes fiers de vous offrir un service de taxi de qualit\u00e9 \u00e0 A\u00e9roport Lyon Saint-Exupery.<\/p>\r\n        <p class=\"landing-page-intro\">Que ce soit pour un trajet local, un transfert vers une gare ou un a\u00e9roport, ou m\u00eame un transport m\u00e9dicalis\u00e9, nous sommes l\u00e0 pour r\u00e9pondre \u00e0 tous vos besoins de d\u00e9placement.<\/p>\r\n\r\n        <h3>Service de Taxi A\u00e9roport Lyon Saint-Exupery<\/h3>\r\n        <p>Nous vous proposons un service de taxi Taxi pour femme \u00e0 A\u00e9roport Lyon Saint-Exupery, assurant rapidit\u00e9, confort et s\u00e9curit\u00e9 pour tous vos trajets. R\u00e9servez facilement votre taxi et profitez d'un transport personnalis\u00e9 adapt\u00e9 \u00e0 vos exigences.<\/p>\r\n        <p>Nous couvrons une large zone autour de A\u00e9roport Lyon Saint-Exupery, incluant des villes comme Bonnefamille, Vaulx-Milieu, La Verpilli\u00e8re, Roche, et bien d'autres. Que vous ayez besoin d'un transport vers Lyon, Vienne, ou d'autres destinations r\u00e9gionales, notre \u00e9quipe est \u00e0 votre disposition.<\/p>\r\n\r\n        <h3>Nos Services<\/h3>\r\n        <ul>\r\n            <li><strong>Transferts vers les gares de Lyon :<\/strong> Que vous voyagiez depuis ou vers Lyon Part-Dieu, Lyon Perrache, ou une autre gare de la r\u00e9gion, nous assurons votre transfert en toute s\u00e9curit\u00e9 et ponctualit\u00e9.<\/li>\r\n            <li><strong>Transferts a\u00e9roportuaires :<\/strong> Profitez de nos services pour vos transferts vers l\u2019a\u00e9roport Lyon Saint-Exup\u00e9ry. Nous garantissons un service de qualit\u00e9 pour tous vos d\u00e9parts et arriv\u00e9es.<\/li>\r\n            <li><strong>Trajets locaux et r\u00e9gionaux :<\/strong> Nous desservons toutes les localit\u00e9s autour de A\u00e9roport Lyon Saint-Exupery, assurant une couverture compl\u00e8te de la r\u00e9gion pour vos d\u00e9placements quotidiens.<\/li>\r\n            <li><strong>Transport m\u00e9dicalis\u00e9 :<\/strong> Notre flotte comprend des v\u00e9hicules adapt\u00e9s pour le transport de patients \u00e0 mobilit\u00e9 r\u00e9duite, assurant confort et s\u00e9curit\u00e9 pour tous vos d\u00e9placements m\u00e9dicaux.<\/li>\r\n        <\/ul>\r\n\r\n        <h3>Engagement envers la Qualit\u00e9<\/h3>\r\n        <p>Chez Taxi A\u00e9roport Lyon Saint-Exupery, nous nous engageons \u00e0 offrir un service de qualit\u00e9 sup\u00e9rieure. Nos v\u00e9hicules sont soumis \u00e0 des contr\u00f4les r\u00e9guliers et nos chauffeurs sont form\u00e9s pour assurer un service professionnel et courtois \u00e0 tout moment.<\/p>\r\n        <p>Nous sommes disponibles 24 heures sur 24, 7 jours sur 7, pour r\u00e9pondre \u00e0 vos besoins de transport \u00e0 toute heure du jour et de la nuit. Vous pouvez compter sur nous pour des trajets s\u00fbrs et fiables \u00e0 chaque fois.<\/p>\r\n\r\n        <h3>Satisfaction Client<\/h3>\r\n        <p>Avec Taxi A\u00e9roport Lyon Saint-Exupery, vous b\u00e9n\u00e9ficiez d'une exp\u00e9rience de transport sans souci. Notre \u00e9quipe d\u00e9vou\u00e9e est l\u00e0 pour rendre vos d\u00e9placements agr\u00e9ables et confortables, quelle que soit votre destination.<\/p>\r\n        <p>Contactez-nous d\u00e8s aujourd'hui pour r\u00e9server votre taxi \u00e0 A\u00e9roport Lyon Saint-Exupery et d\u00e9couvrir pourquoi nous sommes le choix pr\u00e9f\u00e9r\u00e9 pour vos besoins de transport dans la r\u00e9gion.<\/p>\r\n\r\n    \n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0bd436f elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"0bd436f\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-81563e2\" data-id=\"81563e2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fcfa1fd elementor-widget elementor-widget-spacer\" data-id=\"fcfa1fd\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-52e0f99 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"52e0f99\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5703e8f\" data-id=\"5703e8f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d98a55f elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"d98a55f\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-04cd3f1\" data-id=\"04cd3f1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2af2761 elementor-view-stacked elementor-shape-circle elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"2af2761\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-clinic-medical\" viewbox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288 115L69.47 307.71c-1.62 1.46-3.69 2.14-5.47 3.35V496a16 16 0 0 0 16 16h416a16 16 0 0 0 16-16V311.1c-1.7-1.16-3.72-1.82-5.26-3.2zm96 261a8 8 0 0 1-8 8h-56v56a8 8 0 0 1-8 8h-48a8 8 0 0 1-8-8v-56h-56a8 8 0 0 1-8-8v-48a8 8 0 0 1 8-8h56v-56a8 8 0 0 1 8-8h48a8 8 0 0 1 8 8v56h56a8 8 0 0 1 8 8zm186.69-139.72l-255.94-226a39.85 39.85 0 0 0-53.45 0l-256 226a16 16 0 0 0-1.21 22.6L25.5 282.7a16 16 0 0 0 22.6 1.21L277.42 81.63a16 16 0 0 1 21.17 0L527.91 283.9a16 16 0 0 0 22.6-1.21l21.4-23.82a16 16 0 0 0-1.22-22.59z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tConventional taxi\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tTaxi Villefontaine is a licensed taxi group for your medical travel.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-359fa50 elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"359fa50\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md elementor-animation-shrink\" href=\"https:\/\/k-miles.fr\/en\/taxi-conventionne-pour-vos-deplacements-medicaux\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-long-arrow-alt-right\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M313.941 216H12c-6.627 0-12 5.373-12 12v56c0 6.627 5.373 12 12 12h301.941v46.059c0 21.382 25.851 32.09 40.971 16.971l86.059-86.059c9.373-9.373 9.373-24.569 0-33.941l-86.059-86.059c-15.119-15.119-40.971-4.411-40.971 16.971V216z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Learn more<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7477eee\" data-id=\"7477eee\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c05fd36 elementor-view-stacked elementor-shape-circle elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"c05fd36\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plane\" viewbox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M480 192H365.71L260.61 8.06A16.014 16.014 0 0 0 246.71 0h-65.5c-10.63 0-18.3 10.17-15.38 20.39L214.86 192H112l-43.2-57.6c-3.02-4.03-7.77-6.4-12.8-6.4H16.01C5.6 128-2.04 137.78.49 147.88L32 256 .49 364.12C-2.04 374.22 5.6 384 16.01 384H56c5.04 0 9.78-2.37 12.8-6.4L112 320h102.86l-49.03 171.6c-2.92 10.22 4.75 20.4 15.38 20.4h65.5c5.74 0 11.04-3.08 13.89-8.06L365.71 320H480c35.35 0 96-28.65 96-64s-60.65-64-96-64z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAirport transfers\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tAirport transfer to Lyon Saint-Exup\u00e9ry or Grenoble. Our spacious vehicles can accommodate you in a group or family.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58b1870 elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"58b1870\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md elementor-animation-shrink\" href=\"https:\/\/k-miles.fr\/en\/taxi-pour-vos-transferts-vers-les-aeroports-saint-exupery-et-grenoble\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-long-arrow-alt-right\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M313.941 216H12c-6.627 0-12 5.373-12 12v56c0 6.627 5.373 12 12 12h301.941v46.059c0 21.382 25.851 32.09 40.971 16.971l86.059-86.059c9.373-9.373 9.373-24.569 0-33.941l-86.059-86.059c-15.119-15.119-40.971-4.411-40.971 16.971V216z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Learn more<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-4441644\" data-id=\"4441644\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-704d2a3 elementor-view-stacked elementor-shape-circle elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"704d2a3\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-train\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M448 96v256c0 51.815-61.624 96-130.022 96l62.98 49.721C386.905 502.417 383.562 512 376 512H72c-7.578 0-10.892-9.594-4.957-14.279L130.022 448C61.82 448 0 403.954 0 352V96C0 42.981 64 0 128 0h192c65 0 128 42.981 128 96zm-48 136V120c0-13.255-10.745-24-24-24H72c-13.255 0-24 10.745-24 24v112c0 13.255 10.745 24 24 24h304c13.255 0 24-10.745 24-24zm-176 64c-30.928 0-56 25.072-56 56s25.072 56 56 56 56-25.072 56-56-25.072-56-56-56z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tStation transfers\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tTransfers Transfer to the station of your choice in Is\u00e8re, Lyon and the surrounding area. Our spacious trunks will accommodate all your suitcases without problem.stations\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4bbf21a elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"4bbf21a\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md elementor-animation-shrink\" href=\"https:\/\/k-miles.fr\/en\/taxi-pour-vos-transferts-vers-les-gares-de-lyon\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-long-arrow-alt-right\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M313.941 216H12c-6.627 0-12 5.373-12 12v56c0 6.627 5.373 12 12 12h301.941v46.059c0 21.382 25.851 32.09 40.971 16.971l86.059-86.059c9.373-9.373 9.373-24.569 0-33.941l-86.059-86.059c-15.119-15.119-40.971-4.411-40.971 16.971V216z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Learn more<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ec19c99 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"ec19c99\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-f82cc89\" data-id=\"f82cc89\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5bff73d elementor-view-stacked elementor-shape-circle elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"5bff73d\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-car\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M499.99 176h-59.87l-16.64-41.6C406.38 91.63 365.57 64 319.5 64h-127c-46.06 0-86.88 27.63-103.99 70.4L71.87 176H12.01C4.2 176-1.53 183.34.37 190.91l6 24C7.7 220.25 12.5 224 18.01 224h20.07C24.65 235.73 16 252.78 16 272v48c0 16.12 6.16 30.67 16 41.93V416c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-32h256v32c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32v-54.07c9.84-11.25 16-25.8 16-41.93v-48c0-19.22-8.65-36.27-22.07-48H494c5.51 0 10.31-3.75 11.64-9.09l6-24c1.89-7.57-3.84-14.91-11.65-14.91zm-352.06-17.83c7.29-18.22 24.94-30.17 44.57-30.17h127c19.63 0 37.28 11.95 44.57 30.17L384 208H128l19.93-49.83zM96 319.8c-19.2 0-32-12.76-32-31.9S76.8 256 96 256s48 28.71 48 47.85-28.8 15.95-48 15.95zm320 0c-19.2 0-48 3.19-48-15.95S396.8 256 416 256s32 12.76 32 31.9-12.8 31.9-32 31.9z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tDaily journeys\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tFor your daily trips, your shopping days, your shopping or your personal and professional appointments.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-addbd96 elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"addbd96\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md elementor-animation-shrink\" href=\"https:\/\/k-miles.fr\/en\/taxi-pour-vos-trajets-quotidiens\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-long-arrow-alt-right\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M313.941 216H12c-6.627 0-12 5.373-12 12v56c0 6.627 5.373 12 12 12h301.941v46.059c0 21.382 25.851 32.09 40.971 16.971l86.059-86.059c9.373-9.373 9.373-24.569 0-33.941l-86.059-86.059c-15.119-15.119-40.971-4.411-40.971 16.971V216z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Learn more<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-4d6b285\" data-id=\"4d6b285\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-63b8953 elementor-view-stacked elementor-shape-circle elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"63b8953\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-cocktail\" viewbox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M296 464h-56V338.78l168.74-168.73c15.52-15.52 4.53-42.05-17.42-42.05H24.68c-21.95 0-32.94 26.53-17.42 42.05L176 338.78V464h-56c-22.09 0-40 17.91-40 40 0 4.42 3.58 8 8 8h240c4.42 0 8-3.58 8-8 0-22.09-17.91-40-40-40zM432 0c-62.61 0-115.35 40.2-135.18 96h52.54c16.65-28.55 47.27-48 82.64-48 52.93 0 96 43.06 96 96s-43.07 96-96 96c-14.04 0-27.29-3.2-39.32-8.64l-35.26 35.26C379.23 279.92 404.59 288 432 288c79.53 0 144-64.47 144-144S511.53 0 432 0z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tFor your evenings\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tCall us to drive you to your birthday parties, bachelorette parties, festivals.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e69e117 elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"e69e117\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md elementor-animation-shrink\" href=\"https:\/\/k-miles.fr\/en\/taxi-pour-toutes-vos-soirees\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-long-arrow-alt-right\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M313.941 216H12c-6.627 0-12 5.373-12 12v56c0 6.627 5.373 12 12 12h301.941v46.059c0 21.382 25.851 32.09 40.971 16.971l86.059-86.059c9.373-9.373 9.373-24.569 0-33.941l-86.059-86.059c-15.119-15.119-40.971-4.411-40.971 16.971V216z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Learn more<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-a59fbae\" data-id=\"a59fbae\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7bc8783 elementor-view-stacked elementor-shape-circle elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"7bc8783\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-ring\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 64C110.06 64 0 125.91 0 208v98.13C0 384.48 114.62 448 256 448s256-63.52 256-141.87V208c0-82.09-110.06-144-256-144zm0 64c106.04 0 192 35.82 192 80 0 9.26-3.97 18.12-10.91 26.39C392.15 208.21 328.23 192 256 192s-136.15 16.21-181.09 42.39C67.97 226.12 64 217.26 64 208c0-44.18 85.96-80 192-80zM120.43 264.64C155.04 249.93 201.64 240 256 240s100.96 9.93 135.57 24.64C356.84 279.07 308.93 288 256 288s-100.84-8.93-135.57-23.36z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tFor your weddings\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tOpt for the privatization of Taxi Villefontaine to drive you on your wedding day or to transport your guests with complete peace of mind\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6becb1f elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"6becb1f\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md elementor-animation-shrink\" href=\"https:\/\/k-miles.fr\/en\/taxi-pour-vos-mariages\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-long-arrow-alt-right\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M313.941 216H12c-6.627 0-12 5.373-12 12v56c0 6.627 5.373 12 12 12h301.941v46.059c0 21.382 25.851 32.09 40.971 16.971l86.059-86.059c9.373-9.373 9.373-24.569 0-33.941l-86.059-86.059c-15.119-15.119-40.971-4.411-40.971 16.971V216z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Learn more<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-4013","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Taxi pour femme \u00e0 A\u00e9roport Lyon Saint-Exupery - K Miles<\/title>\n<meta name=\"description\" content=\"Taxi pour femme \u00e0 A\u00e9roport Lyon Saint-Exupery - K Miles , votre taxi pour tous vos trajets sur Lyon Saint-Exup\u00e9ry, gares de Lyon et de l&#039;Is\u00e8re.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/k-miles.fr\/en\/taxi-pour-femme-a-aeroport-lyon-saint-exupery\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Taxi pour femme \u00e0 A\u00e9roport Lyon Saint-Exupery - K Miles\" \/>\n<meta property=\"og:description\" content=\"Taxi pour femme \u00e0 A\u00e9roport Lyon Saint-Exupery - K Miles , votre taxi pour tous vos trajets sur Lyon Saint-Exup\u00e9ry, gares de Lyon et de l&#039;Is\u00e8re.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/k-miles.fr\/en\/taxi-pour-femme-a-aeroport-lyon-saint-exupery\/\" \/>\n<meta property=\"og:site_name\" content=\"K Miles\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Taxi-De-Villefontaine\/100089877480571\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/k-miles.fr\/wp-content\/uploads\/2024\/06\/taxi-villefontaine-lyon-saint-exupery.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1587\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/k-miles.fr\\\/taxi-pour-femme-a-aeroport-lyon-saint-exupery\\\/\",\"url\":\"https:\\\/\\\/k-miles.fr\\\/taxi-pour-femme-a-aeroport-lyon-saint-exupery\\\/\",\"name\":\"Taxi pour femme \u00e0 A\u00e9roport Lyon Saint-Exupery - K Miles\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/k-miles.fr\\\/#website\"},\"datePublished\":\"2024-07-06T17:57:16+00:00\",\"description\":\"Taxi pour femme \u00e0 A\u00e9roport Lyon Saint-Exupery - K Miles , votre taxi pour tous vos trajets sur Lyon Saint-Exup\u00e9ry, gares de Lyon et de l'Is\u00e8re.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/k-miles.fr\\\/taxi-pour-femme-a-aeroport-lyon-saint-exupery\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/k-miles.fr\\\/taxi-pour-femme-a-aeroport-lyon-saint-exupery\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/k-miles.fr\\\/taxi-pour-femme-a-aeroport-lyon-saint-exupery\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/k-miles.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Taxi pour femme \u00e0 A\u00e9roport Lyon Saint-Exupery\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/k-miles.fr\\\/#website\",\"url\":\"https:\\\/\\\/k-miles.fr\\\/\",\"name\":\"Taxi Villefontaine\",\"description\":\"Voyagez en premi\u00e8re classe, o\u00f9 que vous alliez, avec Taxi Villefontaine, pour tous vos besoins\",\"publisher\":{\"@id\":\"https:\\\/\\\/k-miles.fr\\\/#organization\"},\"alternateName\":\"Votre taxi sur Lyon, Villefontaine et ses alentours\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/k-miles.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/k-miles.fr\\\/#organization\",\"name\":\"Taxi Villefontaine\",\"alternateName\":\"Votre taxi sur Lyon, Villefontaine et ses alentours\",\"url\":\"https:\\\/\\\/k-miles.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/k-miles.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/k-miles.fr\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/logo-k-miles.png\",\"contentUrl\":\"https:\\\/\\\/k-miles.fr\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/logo-k-miles.png\",\"width\":824,\"height\":317,\"caption\":\"Taxi Villefontaine\"},\"image\":{\"@id\":\"https:\\\/\\\/k-miles.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Taxi-De-Villefontaine\\\/100089877480571\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Taxi pour femme \u00e0 A\u00e9roport Lyon Saint-Exupery - K Miles","description":"Taxi pour femme \u00e0 A\u00e9roport Lyon Saint-Exupery - K Miles , votre taxi pour tous vos trajets sur Lyon Saint-Exup\u00e9ry, gares de Lyon et de l'Is\u00e8re.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/k-miles.fr\/en\/taxi-pour-femme-a-aeroport-lyon-saint-exupery\/","og_locale":"en_US","og_type":"article","og_title":"Taxi pour femme \u00e0 A\u00e9roport Lyon Saint-Exupery - K Miles","og_description":"Taxi pour femme \u00e0 A\u00e9roport Lyon Saint-Exupery - K Miles , votre taxi pour tous vos trajets sur Lyon Saint-Exup\u00e9ry, gares de Lyon et de l'Is\u00e8re.","og_url":"https:\/\/k-miles.fr\/en\/taxi-pour-femme-a-aeroport-lyon-saint-exupery\/","og_site_name":"K Miles","article_publisher":"https:\/\/www.facebook.com\/people\/Taxi-De-Villefontaine\/100089877480571\/","og_image":[{"width":1920,"height":1587,"url":"https:\/\/k-miles.fr\/wp-content\/uploads\/2024\/06\/taxi-villefontaine-lyon-saint-exupery.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/k-miles.fr\/taxi-pour-femme-a-aeroport-lyon-saint-exupery\/","url":"https:\/\/k-miles.fr\/taxi-pour-femme-a-aeroport-lyon-saint-exupery\/","name":"Taxi pour femme \u00e0 A\u00e9roport Lyon Saint-Exupery - K Miles","isPartOf":{"@id":"https:\/\/k-miles.fr\/#website"},"datePublished":"2024-07-06T17:57:16+00:00","description":"Taxi pour femme \u00e0 A\u00e9roport Lyon Saint-Exupery - K Miles , votre taxi pour tous vos trajets sur Lyon Saint-Exup\u00e9ry, gares de Lyon et de l'Is\u00e8re.","breadcrumb":{"@id":"https:\/\/k-miles.fr\/taxi-pour-femme-a-aeroport-lyon-saint-exupery\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/k-miles.fr\/taxi-pour-femme-a-aeroport-lyon-saint-exupery\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/k-miles.fr\/taxi-pour-femme-a-aeroport-lyon-saint-exupery\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/k-miles.fr\/"},{"@type":"ListItem","position":2,"name":"Taxi pour femme \u00e0 A\u00e9roport Lyon Saint-Exupery"}]},{"@type":"WebSite","@id":"https:\/\/k-miles.fr\/#website","url":"https:\/\/k-miles.fr\/","name":"Taxi Villefontaine","description":"Travel first class, wherever you go, with Taxi Villefontaine, for all your needs","publisher":{"@id":"https:\/\/k-miles.fr\/#organization"},"alternateName":"Votre taxi sur Lyon, Villefontaine et ses alentours","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/k-miles.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/k-miles.fr\/#organization","name":"Taxi Villefontaine","alternateName":"Votre taxi sur Lyon, Villefontaine et ses alentours","url":"https:\/\/k-miles.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/k-miles.fr\/#\/schema\/logo\/image\/","url":"https:\/\/k-miles.fr\/wp-content\/uploads\/2024\/06\/logo-k-miles.png","contentUrl":"https:\/\/k-miles.fr\/wp-content\/uploads\/2024\/06\/logo-k-miles.png","width":824,"height":317,"caption":"Taxi Villefontaine"},"image":{"@id":"https:\/\/k-miles.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Taxi-De-Villefontaine\/100089877480571\/"]}]}},"_links":{"self":[{"href":"https:\/\/k-miles.fr\/en\/wp-json\/wp\/v2\/pages\/4013","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/k-miles.fr\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/k-miles.fr\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/k-miles.fr\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/k-miles.fr\/en\/wp-json\/wp\/v2\/comments?post=4013"}],"version-history":[{"count":0,"href":"https:\/\/k-miles.fr\/en\/wp-json\/wp\/v2\/pages\/4013\/revisions"}],"wp:attachment":[{"href":"https:\/\/k-miles.fr\/en\/wp-json\/wp\/v2\/media?parent=4013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}